{"id":2045,"count":1,"description":"","link":"https:\/\/www.blj.co.id\/index.php\/tag\/bank-danamon\/","name":"Bank Danamon","slug":"bank-danamon","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.blj.co.id\/index.php\/wp-json\/wp\/v2\/tags\/2045"}],"collection":[{"href":"https:\/\/www.blj.co.id\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.blj.co.id\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.blj.co.id\/index.php\/wp-json\/wp\/v2\/posts?tags=2045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}