{"id":1755,"count":23,"description":"","link":"https:\/\/www.blj.co.id\/index.php\/category\/directory\/style-directory\/","name":"Style Directory","slug":"style-directory","taxonomy":"category","parent":5827,"meta":[],"_links":{"self":[{"href":"https:\/\/www.blj.co.id\/index.php\/wp-json\/wp\/v2\/categories\/1755"}],"collection":[{"href":"https:\/\/www.blj.co.id\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.blj.co.id\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.blj.co.id\/index.php\/wp-json\/wp\/v2\/categories\/5827"}],"wp:post_type":[{"href":"https:\/\/www.blj.co.id\/index.php\/wp-json\/wp\/v2\/posts?categories=1755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}